{"id":171,"count":12,"description":"","link":"https:\/\/tuyendung-daotao.galaxystudio.vn\/en\/type\/part-time\/","name":"Part-time","slug":"part-time","taxonomy":"iwj_type","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/tuyendung-daotao.galaxystudio.vn\/en\/wp-json\/wp\/v2\/iwj_type\/171"}],"collection":[{"href":"https:\/\/tuyendung-daotao.galaxystudio.vn\/en\/wp-json\/wp\/v2\/iwj_type"}],"about":[{"href":"https:\/\/tuyendung-daotao.galaxystudio.vn\/en\/wp-json\/wp\/v2\/taxonomies\/iwj_type"}],"wp:post_type":[{"href":"https:\/\/tuyendung-daotao.galaxystudio.vn\/en\/wp-json\/wp\/v2\/jobs?iwj_type=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}